{"id":1460,"date":"2025-08-30T22:48:19","date_gmt":"2025-08-30T22:48:19","guid":{"rendered":"https:\/\/my-barcelona-guide.com\/?p=1460"},"modified":"2025-09-02T12:59:29","modified_gmt":"2025-09-02T12:59:29","slug":"espana-y-el-amor-por-las-naranjas","status":"publish","type":"post","link":"https:\/\/my-barcelona-guide.com\/es\/espana-y-el-amor-por-las-naranjas","title":{"rendered":"Espa\u00f1a y el amor por las naranjas"},"content":{"rendered":"\n<p>Cada vez que paseo por las calles de <a href=\"https:\/\/my-barcelona-guide.com\/es\" title=\"\">Barcelona <\/a>y veo naranjos con sus frutos, no dejo de admirarlos y asombrarme por su sencillez, rebosantes de frutos anaranjados, que atraen la mirada incluso de los barceloneses, acostumbrados a ellos desde hace tiempo. \u00a1Y qu\u00e9 decir de los turistas! Sobre el fondo azul del cielo despejado de Espa\u00f1a, estos hermosos \u00e1rboles parecen parte de una imagen vibrante y ex\u00f3tica creada por la naturaleza.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"http:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg\" alt=\"\u0412\u043d\u0443\u0442\u0440\u0435\u043d\u043d\u0438\u0439 \u0434\u0432\u043e\u0440\u0438\u043a \u0432\u043e \u0414\u0432\u043e\u0440\u0446\u0435 \u041a\u043e\u0440\u043e\u043b\u044f \u0432 \u0411\u0430\u0440\u0441\u0435\u043b\u043e\u043d\u0435\" class=\"wp-image-818\" srcset=\"https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg 640w, https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace-300x225.jpeg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n<p>La tradici\u00f3n de decorar calles y plazas con c\u00edtricos lleg\u00f3 a Espa\u00f1a de la mano de los \u00e1rabes a principios del siglo VIII. Los naranjos, originarios de Asia, se adaptaron bien al clima del sur de Espa\u00f1a. Los \u00e1rabes no permanecieron mucho tiempo en el territorio de las actuales Catalu\u00f1a y Barcelona, \u200b\u200bunos 50 a\u00f1os. Para una persona, esto es mucho tiempo, pero para la historia, es un instante. Pero en el sur de Espa\u00f1a, \u00a1permanecieron all\u00ed durante 8 siglos!<\/p>\n\n\n\n<p>En primavera, el aire se impregna del dulce aroma del azahar, la flor del azahar, pero\u2026 como siempre, todo tiene su lado oscuro. Toneladas de fruta amarga, y esta es la variedad amarga y ornamental, que caen de los \u00e1rboles son un dolor de cabeza para el departamento de limpieza de la ciudad. Las naranjas se ven preciosas en el \u00e1rbol, pero una vez que caen y se aplastan, las calles se vuelven pegajosas de jugo. Al parecer, por eso los catalanes, m\u00e1s pr\u00e1cticos, dejaron una cantidad razonable de estos \u00e1rboles en Barcelona, \u200b\u200ben lugar de convertirla en un huerto de naranjos, como, por ejemplo, en Sevilla, en el sur de Espa\u00f1a. Y all\u00ed simplemente no saben c\u00f3mo deshacerse de toneladas de naranjas amargas, que los espa\u00f1oles no comen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mermelada<\/h2>\n\n\n\n<p>Se utilizan para elaborar mermelada, gran parte de la cual se exporta a Gran Breta\u00f1a. Las naranjas de Sevilla tambi\u00e9n son un ingrediente clave en los famosos licores <a href=\"https:\/\/www.cointreau.com\/\" title=\"\">Cointreau<\/a> y Grand Marnier.<\/p>\n\n\n\n<p>Por cierto, los or\u00edgenes de la mermelada est\u00e1n rodeados de mitos y leyendas. La primera receta manuscrita de mermelada se encontr\u00f3 en el castillo de Dunrobin, en Sutherland, en las Tierras Altas de Escocia, en 1683. Cuenta la leyenda que un barco que transportaba naranjas desde Espa\u00f1a se refugi\u00f3 de una tormenta en el puerto de Dundee, y el confitero local James Keiller fue el primero en encontrarle un uso a la fruta. Puede que sea un mito, pero Keiller elabor\u00f3 \u200b\u200bla primera marca comercial de mermelada en 1797.<\/p>\n\n\n\n<p>Y ahora, el zumo de naranjas no deseadas ha encontrado un nuevo uso: se utilizar\u00e1 como biomasa: se utilizar\u00e1 para producir\u2026 electricidad. En Sevilla, Espa\u00f1a, se ha puesto en marcha un programa experimental para utilizar el metano producido como enzima de la fruta para generar electricidad limpia para el suministro de agua de la ciudad.<\/p>\n\n\n\n<p>Una decisi\u00f3n inesperada. Y muy beneficiosa para todos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La historia de los naranjos ornamentales en Espa\u00f1a, introducidos por los \u00e1rabes. Aborda los desaf\u00edos de la fruta amarga, su uso en mermeladas y licores, y un proyecto innovador en Sevilla que genera electricidad a partir del zumo de naranja.<\/p>\n","protected":false},"author":2,"featured_media":821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[105,108,111,101],"class_list":["post-1460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-barcelona-es","tag-spain-es","tag-marmalade-es","tag-oranges-es"],"aioseo_notices":[],"featured_image_urls_v2":{"full":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"thumbnail":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace-150x150.jpeg",150,150,true],"medium":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace-300x225.jpeg",300,225,true],"medium_large":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"large":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"gs-tiny":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",50,38,false],"xl":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"xxl":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"xxxl":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"xxxxl":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"xxxxxl":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"1536x1536":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"2048x2048":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace.jpeg",640,480,false],"onepress-blog-small":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace-300x150.jpeg",300,150,true],"onepress-small":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace-480x300.jpeg",480,300,true],"onepress-medium":["https:\/\/my-barcelona-guide.com\/wp-content\/uploads\/2021\/03\/barcelona-innner-court-kings-palace-640x400.jpeg",640,400,true]},"post_excerpt_stackable_v2":"<p>La historia de los naranjos ornamentales en Espa\u00f1a, introducidos por los \u00e1rabes. Aborda los desaf\u00edos de la fruta amarga, su uso en mermeladas y licores, y un proyecto innovador en Sevilla que genera electricidad a partir del zumo de naranja.<\/p>\n","category_list_v2":"<a href=\"https:\/\/my-barcelona-guide.com\/es\/blog\" rel=\"category tag\">Mi Blog<\/a>","author_info_v2":{"name":"Natalia Usacheva","url":"https:\/\/my-barcelona-guide.com\/es\/author\/natalia-usacheva"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/posts\/1460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/comments?post=1460"}],"version-history":[{"count":0,"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/posts\/1460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/media\/821"}],"wp:attachment":[{"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/media?parent=1460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/categories?post=1460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-barcelona-guide.com\/es\/wp-json\/wp\/v2\/tags?post=1460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}